{"id":143605,"date":"2026-05-04T15:42:16","date_gmt":"2026-05-04T18:42:16","guid":{"rendered":"https:\/\/www.delibresparaelmundo.com.ar\/index.php\/2026\/05\/04\/misterio-en-coghlan-revisan-con-un-georradar-el-jardin-donde-aparecio-el-cuerpo-de-diego-fernandez-lima\/"},"modified":"2026-05-04T15:42:16","modified_gmt":"2026-05-04T18:42:16","slug":"misterio-en-coghlan-revisan-con-un-georradar-el-jardin-donde-aparecio-el-cuerpo-de-diego-fernandez-lima","status":"publish","type":"post","link":"https:\/\/www.delibresparaelmundo.com.ar\/index.php\/2026\/05\/04\/misterio-en-coghlan-revisan-con-un-georradar-el-jardin-donde-aparecio-el-cuerpo-de-diego-fernandez-lima\/","title":{"rendered":"Misterio en Coghlan: revisan con un georradar el jard\u00edn donde apareci\u00f3 el cuerpo de Diego Fern\u00e1ndez Lima"},"content":{"rendered":"<ul>\n<li>Es parte de una serie de medidas con las que se busca reactivar la investigaci\u00f3n que arranc\u00f3 el 20 de mayo de 2025 cuando se descubri\u00f3 el cuerpo del chico de 16 a\u00f1os.<\/li>\n<li>En esa casa vive la familia de Cristian Graf, quien era compa\u00f1ero de colegio de la v\u00edctima al momento de su desaparici\u00f3n, en 1984.<\/li>\n<\/ul>\n<p>Es parte de una serie de medidas con las que se busca reactivar la investigaci\u00f3n que arranc\u00f3 el 20 de mayo de 2025 cuando se descubri\u00f3 el cuerpo del chico de 16 a\u00f1os.En esa casa vive la familia de Cristian Graf, quien era compa\u00f1ero de colegio de la v\u00edctima al momento de su desaparici\u00f3n, en 1984.<\/p>","protected":false},"excerpt":{"rendered":"<p>Es parte de una serie de medidas con las que se busca reactivar la investigaci\u00f3n que arranc\u00f3 el 20 de mayo de 2025 cuando se descubri\u00f3 el cuerpo del chico de 16 a\u00f1os. En esa casa vive la familia de Cristian Graf, quien era compa\u00f1ero de colegio de la v\u00edctima al momento de su desaparici\u00f3n, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":143606,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-143605","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/www.delibresparaelmundo.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/143605","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.delibresparaelmundo.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.delibresparaelmundo.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.delibresparaelmundo.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.delibresparaelmundo.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=143605"}],"version-history":[{"count":0,"href":"https:\/\/www.delibresparaelmundo.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/143605\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.delibresparaelmundo.com.ar\/index.php\/wp-json\/wp\/v2\/media\/143606"}],"wp:attachment":[{"href":"https:\/\/www.delibresparaelmundo.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=143605"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.delibresparaelmundo.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=143605"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.delibresparaelmundo.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=143605"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}