{"id":143661,"date":"2026-05-06T15:41:21","date_gmt":"2026-05-06T18:41:21","guid":{"rendered":"https:\/\/www.delibresparaelmundo.com.ar\/index.php\/2026\/05\/06\/absolvieron-a-cesar-soto-y-sergio-kalenuk-y-el-crimen-de-paulina-lebbos-quedo-impune\/"},"modified":"2026-05-06T15:41:21","modified_gmt":"2026-05-06T18:41:21","slug":"absolvieron-a-cesar-soto-y-sergio-kalenuk-y-el-crimen-de-paulina-lebbos-quedo-impune","status":"publish","type":"post","link":"https:\/\/www.delibresparaelmundo.com.ar\/index.php\/2026\/05\/06\/absolvieron-a-cesar-soto-y-sergio-kalenuk-y-el-crimen-de-paulina-lebbos-quedo-impune\/","title":{"rendered":"Absolvieron a C\u00e9sar Soto y Sergio Kale\u00f1uk y el crimen de Paulina Lebbos qued\u00f3 impune"},"content":{"rendered":"<ul>\n<li>Tras dos d\u00e9cadas de impunidad, este mi\u00e9rcoles se conoci\u00f3 la sentencia en el juicio por el femicidio que marc\u00f3 un antes y un despu\u00e9s en la historia de la provincia.<\/li>\n<li>C\u00e9sar Soto, ex pareja de la estudiante de Comunicaci\u00f3n Social asesinada en febrero de 2006, estaba acusado de homicidio agravado.<\/li>\n<li>Los jueces consideraron que no hay pruebas contra \u00e9l ni contra el hijo del ex secretario de la gobernaci\u00f3n de Jos\u00e9 Alperovich, Alberto Kale\u00f1uk.<\/li>\n<\/ul>\n<p>Tras dos d\u00e9cadas de impunidad, este mi\u00e9rcoles se conoci\u00f3 la sentencia en el juicio por el femicidio que marc\u00f3 un antes y un despu\u00e9s en la historia de la provincia.C\u00e9sar Soto, ex pareja de la estudiante de Comunicaci\u00f3n Social asesinada en febrero de 2006, estaba acusado de homicidio agravado.Los jueces consideraron que no hay pruebas contra \u00e9l ni contra el hijo del ex secretario de la gobernaci\u00f3n de Jos\u00e9 Alperovich, Alberto Kale\u00f1uk.<\/p>","protected":false},"excerpt":{"rendered":"<p>Tras dos d\u00e9cadas de impunidad, este mi\u00e9rcoles se conoci\u00f3 la sentencia en el juicio por el femicidio que marc\u00f3 un antes y un despu\u00e9s en la historia de la provincia. C\u00e9sar Soto, ex pareja de la estudiante de Comunicaci\u00f3n Social asesinada en febrero de 2006, estaba acusado de homicidio agravado. Los jueces consideraron que no [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":143662,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-143661","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/www.delibresparaelmundo.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/143661","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.delibresparaelmundo.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.delibresparaelmundo.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.delibresparaelmundo.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.delibresparaelmundo.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=143661"}],"version-history":[{"count":0,"href":"https:\/\/www.delibresparaelmundo.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/143661\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.delibresparaelmundo.com.ar\/index.php\/wp-json\/wp\/v2\/media\/143662"}],"wp:attachment":[{"href":"https:\/\/www.delibresparaelmundo.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=143661"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.delibresparaelmundo.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=143661"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.delibresparaelmundo.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=143661"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}