{"id":143706,"date":"2026-05-08T15:42:28","date_gmt":"2026-05-08T18:42:28","guid":{"rendered":"https:\/\/www.delibresparaelmundo.com.ar\/index.php\/2026\/05\/08\/una-luz-en-el-cielo-el-pentagono-publica-nuevos-archivos-sobre-ovnis-y-afirma-que-el-publico-puede-sacar-sus-propias-conclusiones\/"},"modified":"2026-05-08T15:42:28","modified_gmt":"2026-05-08T18:42:28","slug":"una-luz-en-el-cielo-el-pentagono-publica-nuevos-archivos-sobre-ovnis-y-afirma-que-el-publico-puede-sacar-sus-propias-conclusiones","status":"publish","type":"post","link":"https:\/\/www.delibresparaelmundo.com.ar\/index.php\/2026\/05\/08\/una-luz-en-el-cielo-el-pentagono-publica-nuevos-archivos-sobre-ovnis-y-afirma-que-el-publico-puede-sacar-sus-propias-conclusiones\/","title":{"rendered":"\u00abUna luz en el cielo\u00bb: el Pent\u00e1gono publica nuevos archivos sobre ovnis y afirma que el p\u00fablico puede sacar sus propias conclusiones"},"content":{"rendered":"<ul>\n<li>Abri\u00f3 un sitio donde figuran los documentos sobre fen\u00f3menos an\u00f3malos no identificados. Ya public\u00f3 unos 162 archivos y promete m\u00e1s.<\/li>\n<li>Adem\u00e1s del Pent\u00e1gono, el esfuerzo est\u00e1 liderado por la Casa Blanca, el director de Inteligencia Nacional, el Departamento de Energ\u00eda, la NASA y el FBI.<\/li>\n<\/ul>\n<p>Abri\u00f3 un sitio donde figuran los documentos sobre fen\u00f3menos an\u00f3malos no identificados. Ya public\u00f3 unos 162 archivos y promete m\u00e1s.Adem\u00e1s del Pent\u00e1gono, el esfuerzo est\u00e1 liderado por la Casa Blanca, el director de Inteligencia Nacional, el Departamento de Energ\u00eda, la NASA y el FBI.<\/p>","protected":false},"excerpt":{"rendered":"<p>Abri\u00f3 un sitio donde figuran los documentos sobre fen\u00f3menos an\u00f3malos no identificados. Ya public\u00f3 unos 162 archivos y promete m\u00e1s. Adem\u00e1s del Pent\u00e1gono, el esfuerzo est\u00e1 liderado por la Casa Blanca, el director de Inteligencia Nacional, el Departamento de Energ\u00eda, la NASA y el FBI. Abri\u00f3 un sitio donde figuran los documentos sobre fen\u00f3menos an\u00f3malos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[623],"tags":[],"class_list":["post-143706","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacionales"],"_links":{"self":[{"href":"https:\/\/www.delibresparaelmundo.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/143706","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.delibresparaelmundo.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.delibresparaelmundo.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.delibresparaelmundo.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.delibresparaelmundo.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=143706"}],"version-history":[{"count":0,"href":"https:\/\/www.delibresparaelmundo.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/143706\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.delibresparaelmundo.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=143706"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.delibresparaelmundo.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=143706"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.delibresparaelmundo.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=143706"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}