{"id":143722,"date":"2026-05-09T03:42:39","date_gmt":"2026-05-09T06:42:39","guid":{"rendered":"https:\/\/www.delibresparaelmundo.com.ar\/index.php\/2026\/05\/09\/nuevo-ataque-de-las-fuerzas-armadas-de-ee-uu-a-una-lancha-que-supuestamente-llevaba-drogas-hay-dos-muertos-y-un-sobreviviente\/"},"modified":"2026-05-09T03:42:39","modified_gmt":"2026-05-09T06:42:39","slug":"nuevo-ataque-de-las-fuerzas-armadas-de-ee-uu-a-una-lancha-que-supuestamente-llevaba-drogas-hay-dos-muertos-y-un-sobreviviente","status":"publish","type":"post","link":"https:\/\/www.delibresparaelmundo.com.ar\/index.php\/2026\/05\/09\/nuevo-ataque-de-las-fuerzas-armadas-de-ee-uu-a-una-lancha-que-supuestamente-llevaba-drogas-hay-dos-muertos-y-un-sobreviviente\/","title":{"rendered":"Nuevo ataque de las Fuerzas Armadas de EE.UU. a una lancha que supuestamente llevaba drogas: hay dos muertos y un sobreviviente"},"content":{"rendered":"<ul>\n<li>La informaci\u00f3n fue brindada por las autoridades estadounidenses y subieron a las redes un video donde se ve el ataque. <\/li>\n<li>La Casa Blanca anunci\u00f3 el mi\u00e9rcoles que el presidente Trump hab\u00eda dado su aprobaci\u00f3n a una nueva estrategia para eliminar a los c\u00e1rteles de la droga en el hemisferio occidental.<\/li>\n<\/ul>\n<p>La informaci\u00f3n fue brindada por las autoridades estadounidenses y subieron a las redes un video donde se ve el ataque. La Casa Blanca anunci\u00f3 el mi\u00e9rcoles que el presidente Trump hab\u00eda dado su aprobaci\u00f3n a una nueva estrategia para eliminar a los c\u00e1rteles de la droga en el hemisferio occidental.<\/p>","protected":false},"excerpt":{"rendered":"<p>La informaci\u00f3n fue brindada por las autoridades estadounidenses y subieron a las redes un video donde se ve el ataque. La Casa Blanca anunci\u00f3 el mi\u00e9rcoles que el presidente Trump hab\u00eda dado su aprobaci\u00f3n a una nueva estrategia para eliminar a los c\u00e1rteles de la droga en el hemisferio occidental. La informaci\u00f3n fue brindada por [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[623],"tags":[],"class_list":["post-143722","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacionales"],"_links":{"self":[{"href":"https:\/\/www.delibresparaelmundo.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/143722","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.delibresparaelmundo.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.delibresparaelmundo.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.delibresparaelmundo.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.delibresparaelmundo.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=143722"}],"version-history":[{"count":0,"href":"https:\/\/www.delibresparaelmundo.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/143722\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.delibresparaelmundo.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=143722"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.delibresparaelmundo.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=143722"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.delibresparaelmundo.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=143722"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}