{"id":143729,"date":"2026-05-09T03:42:39","date_gmt":"2026-05-09T06:42:39","guid":{"rendered":"https:\/\/www.delibresparaelmundo.com.ar\/index.php\/2026\/05\/09\/encomiendas-con-cocaina-de-ezeiza-a-paris-aduana-libero-el-envio-de-dos-paquetes-con-droga-pero-era-una-trampa-y-desmantelaron-una-red-narco\/"},"modified":"2026-05-09T03:42:39","modified_gmt":"2026-05-09T06:42:39","slug":"encomiendas-con-cocaina-de-ezeiza-a-paris-aduana-libero-el-envio-de-dos-paquetes-con-droga-pero-era-una-trampa-y-desmantelaron-una-red-narco","status":"publish","type":"post","link":"https:\/\/www.delibresparaelmundo.com.ar\/index.php\/2026\/05\/09\/encomiendas-con-cocaina-de-ezeiza-a-paris-aduana-libero-el-envio-de-dos-paquetes-con-droga-pero-era-una-trampa-y-desmantelaron-una-red-narco\/","title":{"rendered":"Encomiendas con coca\u00edna de Ezeiza a Par\u00eds: Aduana liber\u00f3 el env\u00edo de dos paquetes con droga, pero era una trampa y desmantelaron una red narco"},"content":{"rendered":"<ul>\n<li>El cargamento fue detectado por Aduana en Buenos Aires. La Justicia implement\u00f3 una \u00abentrega vigilada\u00bb para atrapar a los responsables de la banda.<\/li>\n<li>Hay tres franceses detenidos: dos en Montevideo y uno en Par\u00eds.<\/li>\n<\/ul>\n<p>El cargamento fue detectado por Aduana en Buenos Aires. La Justicia implement\u00f3 una \u00abentrega vigilada\u00bb para atrapar a los responsables de la banda.Hay tres franceses detenidos: dos en Montevideo y uno en Par\u00eds.<\/p>","protected":false},"excerpt":{"rendered":"<p>El cargamento fue detectado por Aduana en Buenos Aires. La Justicia implement\u00f3 una \u00abentrega vigilada\u00bb para atrapar a los responsables de la banda. Hay tres franceses detenidos: dos en Montevideo y uno en Par\u00eds. El cargamento fue detectado por Aduana en Buenos Aires. La Justicia implement\u00f3 una \u00abentrega vigilada\u00bb para atrapar a los responsables de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":143730,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-143729","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/www.delibresparaelmundo.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/143729","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.delibresparaelmundo.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.delibresparaelmundo.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.delibresparaelmundo.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.delibresparaelmundo.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=143729"}],"version-history":[{"count":0,"href":"https:\/\/www.delibresparaelmundo.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/143729\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.delibresparaelmundo.com.ar\/index.php\/wp-json\/wp\/v2\/media\/143730"}],"wp:attachment":[{"href":"https:\/\/www.delibresparaelmundo.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=143729"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.delibresparaelmundo.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=143729"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.delibresparaelmundo.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=143729"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}