{"id":143741,"date":"2026-05-09T15:41:08","date_gmt":"2026-05-09T18:41:08","guid":{"rendered":"https:\/\/www.delibresparaelmundo.com.ar\/index.php\/2026\/05\/09\/timon-y-las-bestias-el-borrador-de-shakespeare-que-habla-sobre-la-crueldad-en-los-vinculos-humanos\/"},"modified":"2026-05-09T15:41:08","modified_gmt":"2026-05-09T18:41:08","slug":"timon-y-las-bestias-el-borrador-de-shakespeare-que-habla-sobre-la-crueldad-en-los-vinculos-humanos","status":"publish","type":"post","link":"https:\/\/www.delibresparaelmundo.com.ar\/index.php\/2026\/05\/09\/timon-y-las-bestias-el-borrador-de-shakespeare-que-habla-sobre-la-crueldad-en-los-vinculos-humanos\/","title":{"rendered":"Tim\u00f3n y las bestias: el \u00abborrador\u00bb de Shakespeare que habla sobre la crueldad en los v\u00ednculos humanos"},"content":{"rendered":"<ul>\n<li>La adaptaci\u00f3n de Alejandro Viola sobre \u00abTim\u00f3n de Atenas\u00bb se presenta los s\u00e1bados de mayo en la sala Boedo de Timbre 4.<\/li>\n<li>Tras un accidente que lo oblig\u00f3 a hacer reposo, el l\u00edder de Los amados rescat\u00f3 una de las historias m\u00e1s oscuras de El bardo.<\/li>\n<\/ul>\n<p>La adaptaci\u00f3n de Alejandro Viola sobre \u00abTim\u00f3n de Atenas\u00bb se presenta los s\u00e1bados de mayo en la sala Boedo de Timbre 4.Tras un accidente que lo oblig\u00f3 a hacer reposo, el l\u00edder de Los amados rescat\u00f3 una de las historias m\u00e1s oscuras de El bardo.<\/p>","protected":false},"excerpt":{"rendered":"<p>La adaptaci\u00f3n de Alejandro Viola sobre \u00abTim\u00f3n de Atenas\u00bb se presenta los s\u00e1bados de mayo en la sala Boedo de Timbre 4. Tras un accidente que lo oblig\u00f3 a hacer reposo, el l\u00edder de Los amados rescat\u00f3 una de las historias m\u00e1s oscuras de El bardo. La adaptaci\u00f3n de Alejandro Viola sobre \u00abTim\u00f3n de Atenas\u00bb [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-143741","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-espectaculo"],"_links":{"self":[{"href":"https:\/\/www.delibresparaelmundo.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/143741","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.delibresparaelmundo.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.delibresparaelmundo.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.delibresparaelmundo.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.delibresparaelmundo.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=143741"}],"version-history":[{"count":0,"href":"https:\/\/www.delibresparaelmundo.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/143741\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.delibresparaelmundo.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=143741"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.delibresparaelmundo.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=143741"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.delibresparaelmundo.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=143741"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}