{"id":143823,"date":"2026-05-12T15:41:08","date_gmt":"2026-05-12T18:41:08","guid":{"rendered":"https:\/\/www.delibresparaelmundo.com.ar\/index.php\/2026\/05\/12\/la-serie-de-wanda-y-maxi-no-representa-la-vuelta-de-la-ficcion-a-la-tv-ni-mucho-menos-como-fue-el-debut-de-una-historia-ultra-corta-creada-para-redes\/"},"modified":"2026-05-12T15:41:08","modified_gmt":"2026-05-12T18:41:08","slug":"la-serie-de-wanda-y-maxi-no-representa-la-vuelta-de-la-ficcion-a-la-tv-ni-mucho-menos-como-fue-el-debut-de-una-historia-ultra-corta-creada-para-redes","status":"publish","type":"post","link":"https:\/\/www.delibresparaelmundo.com.ar\/index.php\/2026\/05\/12\/la-serie-de-wanda-y-maxi-no-representa-la-vuelta-de-la-ficcion-a-la-tv-ni-mucho-menos-como-fue-el-debut-de-una-historia-ultra-corta-creada-para-redes\/","title":{"rendered":"La serie de Wanda y Maxi no representa la vuelta de la ficci\u00f3n a la TV, ni mucho menos: c\u00f3mo fue el debut de una historia ultra corta creada para redes"},"content":{"rendered":"<ul>\n<li>\u00abTri\u00e1ngulo amoroso\u00bb es una seguidilla de sketches con gui\u00f1os a su verdadera historia de amor y desamor. <\/li>\n<li>Imposible analizarla como una ficci\u00f3n, porque la nueva serie \u00abvertical\u00bb de Telefe, que tuvo doble estreno, por las plataformas y por aire, tiene una larga escena por cap\u00edtulo y nada m\u00e1s. <\/li>\n<li>El primero, que se vio entre \u00abPasapalabra\u00bb y \u00abGH\u00bb, dur\u00f3 menos de un minuto y medio.<\/li>\n<li>Tiene m\u00e1s aroma a parodia que a trama: el lado B de una de las parejas m\u00e1s medi\u00e1ticas de los \u00faltimos a\u00f1os que hacen de ellos mismos. <\/li>\n<\/ul>\n<p>\u00abTri\u00e1ngulo amoroso\u00bb es una seguidilla de sketches con gui\u00f1os a su verdadera historia de amor y desamor. Imposible analizarla como una ficci\u00f3n, porque la nueva serie \u00abvertical\u00bb de Telefe, que tuvo doble estreno, por las plataformas y por aire, tiene una larga escena por cap\u00edtulo y nada m\u00e1s. El primero, que se vio entre \u00abPasapalabra\u00bb y \u00abGH\u00bb, dur\u00f3 menos de un minuto y medio.Tiene m\u00e1s aroma a parodia que a trama: el lado B de una de las parejas m\u00e1s medi\u00e1ticas de los \u00faltimos a\u00f1os que hacen de ellos mismos.<\/p>","protected":false},"excerpt":{"rendered":"<p>\u00abTri\u00e1ngulo amoroso\u00bb es una seguidilla de sketches con gui\u00f1os a su verdadera historia de amor y desamor. Imposible analizarla como una ficci\u00f3n, porque la nueva serie \u00abvertical\u00bb de Telefe, que tuvo doble estreno, por las plataformas y por aire, tiene una larga escena por cap\u00edtulo y nada m\u00e1s. El primero, que se vio entre \u00abPasapalabra\u00bb [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-143823","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-espectaculo"],"_links":{"self":[{"href":"https:\/\/www.delibresparaelmundo.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/143823","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.delibresparaelmundo.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.delibresparaelmundo.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.delibresparaelmundo.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.delibresparaelmundo.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=143823"}],"version-history":[{"count":0,"href":"https:\/\/www.delibresparaelmundo.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/143823\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.delibresparaelmundo.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=143823"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.delibresparaelmundo.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=143823"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.delibresparaelmundo.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=143823"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}